{"id":141,"date":"2017-12-03T00:28:00","date_gmt":"2017-12-03T02:28:00","guid":{"rendered":"http:\/\/equipashow.com.br\/ver2\/?p=141"},"modified":"2022-01-01T10:00:30","modified_gmt":"2022-01-01T13:00:30","slug":"iluminacao-computadorizada-i-o-que-e-dmx-512","status":"publish","type":"post","link":"https:\/\/equipashow.com.br\/ver2\/arquivos\/141","title":{"rendered":"Ilumina\u00e7\u00e3o Computadorizada I &#8211; O que \u00e9 DMX-512"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">TEMPO DE LEITURA ESTIMADO:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">MINUTOS<\/span><\/span><p style=\"text-align: justify;\">Ol\u00e1, vou falar um pouco sobre este termo, que tanto assombra as especifica\u00e7\u00f5es de aparelhos de ilumina\u00e7\u00e3o, e que tanto confunde as pessoas e principalmente os pequenos usu\u00e1rios de ilumina\u00e7\u00e3o. Neste primeiro artigo, vou dar uma introdu\u00e7\u00e3o do que \u00e9, para que serve, suas vantagens e suas desvantagens, enfim, uma passada pelo conceito deste maravilhoso protocolo de comunica\u00e7\u00e3o DMX-512.<\/p>\n<p style=\"text-align: justify;\">DMX-512 \u00e9 um protocolo que foi criado para possibilitar a comunica\u00e7\u00e3o entre dispositivos de ilumina\u00e7\u00e3o. Utilizo os termos mesa, console e controller para me referir a dispositivos que enviam sinais DMX-512. Os termos dimmer e scan, s\u00e3o utilizados por serem comuns, por\u00e9m, s\u00e3o os aparelhos como uma maquina de fuma\u00e7a, scan, moving head por exemplo os que mais se difundiram neste ramo, com este protocolo.<\/p>\n<h1 style=\"text-align: justify;\">Defini\u00e7\u00e3o:<\/h1>\n<p style=\"text-align: justify;\">DMX-512 \u00e9 um padr\u00e3o criado especificamente para a comunica\u00e7\u00e3o entre dispositivos de ilumina\u00e7\u00e3o, e define suas regras de comunica\u00e7\u00e3o e interliga\u00e7\u00e3o. Como outros padr\u00f5es por exemplo o USB para computadores, a RS-232 e a RS-485 (esta ultima muito parecida com o DMX-512), o padr\u00e3o Ethernet entre muito outros, posso at\u00e9 me arriscar a dizer que como o PORTUGU\u00caS ou o INGL\u00caS, para ser mais insistente, vejamos o porque mais adiante.<\/p>\n<h1 style=\"text-align: justify;\">Hist\u00f3rico:<\/h1>\n<p style=\"text-align: justify;\">Antes do DMX-512 surgir, outros padr\u00f5es para a comunica\u00e7\u00e3o de dispositivos j\u00e1 existiam, como o 0-10VDC anal\u00f3gico, por\u00e9m, em 1986 o Instituto de Teatro e Tecnologia dos EUA definiu uma maneira de comunica\u00e7\u00e3o entre consoles e dimmers (mesa e Rack).<\/p>\n<p style=\"text-align: justify;\">Pequenas revis\u00f5es foram feitas em 1990, para consertar problemas e criar melhorias. Em 1998 foi iniciada a revis\u00e3o para dar suporte n\u00e3o s\u00f3 a mesas e racks, m\u00e1s tamb\u00e9m, a outros aparelhos como scanners e moving heads e maquinas de fuma\u00e7a.<\/p>\n<h1 style=\"text-align: justify;\">Funcionamento:<\/h1>\n<p style=\"text-align: justify;\">No padr\u00e3o anal\u00f3gico, 0-10VDC, cada canal \u00e9 comandado por um fio, ent\u00e3o, 24 canais dimmer, significa ter 24 fios ligados ao rack e mais 1 de referencia ou aterramento, tornando o cabeamento complexo e caro, fora os problemas com loops de terra e ru\u00eddos gerados. Por outro lado, um \u00fanico cabo DMX-512 pode trafegar 512 canais, e com a comunica\u00e7\u00e3o digital, ru\u00eddos n\u00e3o s\u00e3o reconhecidos pelos aparelhos e dispositivos.<\/p>\n<p style=\"text-align: justify;\">A comunica\u00e7\u00e3o \u00e9 feita de forma serial a raz\u00e3o de 250kbps (250 kilobits por segundo) o que permite o trafego de 40 pacotes de 512 canais a cada segundo. Quando mais de 512 canais s\u00e3o necess\u00e1rios, podem-se utilizar diversos consoles ou ent\u00e3o consoles com mais de 1 sa\u00edda DMX-512, como a AVOLITES PEAR 2004 que possui 4 sa\u00eddas e controla 2048 canais DMX.<\/p>\n<h1 style=\"text-align: justify;\">Caracter\u00edsticas El\u00e9tricas:<\/h1>\n<p style=\"text-align: justify;\">O DMX-512 tem as mesmas caracter\u00edsticas do padr\u00e3o EIA-485 ou RS-485 e significa que os mesmos cabos podem ser utilizados, um DRIVER DMX envia sinal utilizando um par complementar de fios, quando 1 est\u00e1 no n\u00edvel alto (1) o outro est\u00e1 no n\u00edvel baixo (0) como ambos os fios detectaram ru\u00eddo, um circuito eletr\u00f4nico no RECEIVER se encarrega de rejeita-lo fazendo uma subtra\u00e7\u00e3o entre os dois sinais, como nos cabos balanceados de \u00e1udio.<\/p>\n<p style=\"text-align: justify;\">O driver precisa fornecer no minimo, 1,5V de tens\u00e3o diferencial e os receivers precisam de 200mV para detectar que n\u00e3o existam erros de comunica\u00e7\u00e3o. O cabeamento deve seguir a norma EIA485, ou uma grande quantidade de ru\u00eddo pode ser gerada fazendo com que a seguran\u00e7a do sistema possa ser seriamente comprometida.<\/p>\n<h1 style=\"text-align: justify;\">Conectores:<\/h1>\n<p style=\"text-align: justify;\">Os conectores devem ser XLR de 5 pinos, onde cada pino serve de:<br \/>\n<strong>1-COMMON<\/strong> (sinal comum ou refer\u00eancia, n\u00e3o \u00e9 terra e n\u00e3o deve ser conectado na carca\u00e7a do conector, ligar este pino ao terra pode gerar problemas em dispositivos com entrada\/sa\u00edda isolada ou flutuante.<br \/>\n<strong>2-Data Minus<\/strong> (serial invertido DATA-)<br \/>\n<strong>3-Data Plus<\/strong> (serial n\u00e3o invertido DATA+)<br \/>\n4-Reservado alguns fabricantes transmitem o segundo universo DMX com DATA-<br \/>\n5-Reservado alguns fabricantes transmitem o segundo universo DMX com DATA+<br \/>\nComo os conectores XLR de 5 pinos s\u00e3o complicados de encontrar e caros, alguns usu\u00e1rios passaram a utilizar o XLR de 3 pinos, e os fabricantes passaram a utilizar esses conectores, com os mesmos dados nos pinos 1,2,3.<\/p>\n<p style=\"text-align: justify;\">Diferente dos conectores de \u00e1udio o XLR f\u00eamea \u00e9 a sa\u00edda e o macho a entrada de sinal por padr\u00e3o da ind\u00fastria.<\/p>\n<h1 style=\"text-align: justify;\">Cabos:<\/h1>\n<p style=\"text-align: justify;\">Os cabos utilizados devem ser os mesmos para EIA845, apesar dos cabos de microfone estarem largamente dispon\u00edveis, possuem capacit\u00e2ncia muito alta e imped\u00e2ncia n\u00e3o adequada para a comunica\u00e7\u00e3o digital de dados.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o utilizar os cabos corretos, n\u00e3o significa que os dispositivos deixem de funcionar, mais sim que funcionem de forma incorreta dependendo da dist\u00e2ncia percorrida e de outros fatores da instala\u00e7\u00e3o.<\/p>\n<h1 style=\"text-align: justify;\">Conex\u00e3o:<\/h1>\n<p style=\"text-align: justify;\">A maioria dos dispositivos receptores de DMX possuem entrada (input) e sa\u00edda (output).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-137 alignleft\" src=\"https:\/\/equipashow.com.br\/ver2\/wp-content\/uploads\/2017\/12\/EsquemaDMX512.gif\" alt=\"\" width=\"335\" height=\"258\" \/>A maneira correta de ligar dispositivos DMX \u00e9 usar o exemplo MESA-&gt;DISPOSITIVO1-&gt;Dispositivo2-&gt;TERMINA\u00c7\u00c3O e ser\u00e1 discutido mais adiante.<\/p>\n<p style=\"text-align: justify;\">Note que o sinal sai da mesa, passa pelo primeiro aparelho ou dispositivo, sai do dispositivo e entra no pr\u00f3ximo dispositivo e assim sucessivamente. \u00c9 proibido utilizar cabos Y em DMX-512, caso a liga\u00e7\u00e3o de um a outro seja complicada, deve-se utilizar um aparelho chamado de BUFFER, que ser\u00e1 explicado daqui a pouco. Na imagem colorido de Vermelho. O dispositivo em verde seria o gerador de sinal ou mesa.<\/p>\n<h1 style=\"text-align: justify;\">Termina\u00e7\u00e3o:<\/h1>\n<p style=\"text-align: justify;\">Um item esquecido ou simplesmente ignorado nas liga\u00e7\u00f5es de aparelhos \u00e9 a termina\u00e7\u00e3o, e \u00e9 simplesmente um resistor ligado entre os conectores 2 e 3 do cabo ligado ao ultimo dispositivo. Ela pode ser feita soldando-se um resistor de 120Ohms a um conector XLR macho.<\/p>\n<p style=\"text-align: justify;\">Alguns dispositivos possuem uma chave, que seleciona se ele deve ou n\u00e3o ser uma termina\u00e7\u00e3o, caso esse aparelho seja o ultimo da linha, deixe esta chave na posi\u00e7\u00e3o ligada, caso n\u00e3o seja, deixe-a desligada.<\/p>\n<p style=\"text-align: justify;\">A termina\u00e7\u00e3o \u00e9 importante, pois garante que o sinal n\u00e3o retorne para a linha (cabo) transmitindo ru\u00eddos e garantindo um melhor funcionamento dos dispositivos.<\/p>\n<hr \/>\n<p>Algumas d\u00favidas respondidas sobre o artigo:<\/p>\n<p>Nome: Sandro Seleguini<br \/>\nPergunta: Ola, s\u00f3 para eu entender eu vou ligar a mesa e 1 aparelho sendo que tenho 5 ai eu puxo com cabos de um aparelho para o outro e selecionando os canais eu seleciono qual funcionara isso somente com um cabo saindo da mesa dmx e ligando de um aparelho no outro mesmo sendo aparelhos diferentes ?<br \/>\nResposta:Exatamente!<\/p>\n<p>Nome: Luiz Eduardo Campos<br \/>\nTexto: Ol\u00e1, gostaria de saber o nome e se for do conhecimento de aparelhos que por meio de um cabo XLR interligam os dimmers box ao computador que assim com uma programa de mesa comanda todos os refletores. Ficarei muito agradecido pela aten\u00e7\u00e3o e se n\u00e3o for pedir demais gostaria de saber se este dispositivo junto com um programa de ilumina\u00e7\u00e3o para Win 7 x64. Agradecido. Muitas luz para n\u00f3s Eduardo Campos<br \/>\nResposta:Este tipo de aparelho, chama-se INTERFACE DMX ou USB DMX.<\/p>\n<p>Nome: pedro<br \/>\nTexto: Ol\u00e1 gostaria de saber se posso ligar 4 elipoidal em uma mesa DMX, ou se ela funciona somente para equipamentos com func\u00f5es dmx, ex: movie light par led laser No momento \u00e9 isso, abra\u00e7os.<br \/>\nResposta:Teria que ligar a mesa DMX no RACK DMX e os elipsoidais no RACK. Atualmente temos algumas op\u00e7\u00f5es de elipso que recebem o sinal dmx diretamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">TEMPO DE LEITURA ESTIMADO:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">MINUTOS<\/span><\/span>Como \u00e9 o funcionamento b\u00e1sico de um sistema DMX-512, as formas de liga\u00e7\u00e3o, tipos de aparelho e o hist\u00f3rico do protocolo mais usado no mundo para controle c\u00eanico<\/p>\n","protected":false},"author":1,"featured_media":137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[55,56,48,49,59,58,57],"class_list":["post-141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iluminacao-profissional-e-arquitetural","tag-dmx","tag-dmx-512","tag-efeitos-especiais","tag-equipamentos-de-iluminacao","tag-iluminacao-computadorizada","tag-ligacao-dmx","tag-protocolo-dmx"],"_links":{"self":[{"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/posts\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":0,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/posts\/141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/media\/137"}],"wp:attachment":[{"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/media?parent=141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/categories?post=141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipashow.com.br\/ver2\/wp-json\/wp\/v2\/tags?post=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}